{"id":1412,"date":"2016-11-19T17:14:57","date_gmt":"2016-11-19T16:14:57","guid":{"rendered":"https:\/\/www.perspectivasanomalas.org\/?post_type=give_forms&#038;p=1412"},"modified":"2019-05-02T02:09:45","modified_gmt":"2019-05-02T01:09:45","slug":"edicion-y-subtitulacion-video-giorgio-antonucci","status":"publish","type":"give_forms","link":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/","title":{"rendered":"CROWDFUNDING Espacio e ideas: Edici\u00f3n y subtitulaci\u00f3n del v\u00eddeo de nuestra entrevista a Giorgio Antonucci"},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1607,"template":"","class_list":["post-1412","give_forms","type-give_forms","status-publish","has-post-thumbnail"],"acf":[],"yoast_head":"\n<title>Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci<\/title>\n<meta name=\"description\" content=\"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci\" \/>\n<meta property=\"og:description\" content=\"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/\" \/>\n<meta property=\"og:site_name\" content=\"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/perspectivasanomalas\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-02T01:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@perspanomalas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/\",\"url\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/\",\"name\":\"Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci\",\"isPartOf\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg\",\"datePublished\":\"2016-11-19T16:14:57+00:00\",\"dateModified\":\"2019-05-02T01:09:45+00:00\",\"description\":\"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage\",\"url\":\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg\",\"contentUrl\":\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg\",\"width\":735,\"height\":553},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.perspectivasanomalas.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donation Forms\",\"item\":\"https:\/\/www.perspectivasanomalas.org\/en\/donations\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CROWDFUNDING Espacio e ideas: Edici\u00f3n y subtitulaci\u00f3n del v\u00eddeo de nuestra entrevista a Giorgio Antonucci\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#website\",\"url\":\"https:\/\/www.perspectivasanomalas.org\/\",\"name\":\"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas\",\"description\":\"An\u00e1lisis del espacio para entender nuestra \u00e9poca. Cr\u00edtica de la sociedad neoliberal.\",\"publisher\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#organization\"},\"alternateName\":\"Perspectivas an\u00f3malas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.perspectivasanomalas.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#organization\",\"name\":\"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas\",\"alternateName\":\"Perspectivas an\u00f3malas\",\"url\":\"https:\/\/www.perspectivasanomalas.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2024\/05\/cropped-Group-52.png\",\"contentUrl\":\"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2024\/05\/cropped-Group-52.png\",\"width\":512,\"height\":512,\"caption\":\"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas\"},\"image\":{\"@id\":\"https:\/\/www.perspectivasanomalas.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/perspectivasanomalas\/\",\"https:\/\/x.com\/perspanomalas\",\"https:\/\/www.linkedin.com\/company\/perspectivas-an\u00f3malas\"]}]}<\/script>\n","yoast_head_json":{"title":"Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci","description":"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci","og_description":"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.","og_url":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/","og_site_name":"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas","article_publisher":"https:\/\/www.facebook.com\/perspectivasanomalas\/","article_modified_time":"2019-05-02T01:09:45+00:00","og_image":[{"width":735,"height":553,"url":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@perspanomalas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/","url":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/","name":"Crowdfunding | Edici\u00f3n y subtitulaci\u00f3n v\u00eddeo Giorgio Antonucci","isPartOf":{"@id":"https:\/\/www.perspectivasanomalas.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage"},"image":{"@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg","datePublished":"2016-11-19T16:14:57+00:00","dateModified":"2019-05-02T01:09:45+00:00","description":"Crowdfunding para la edici\u00f3n y subtitulaci\u00f3n en castellano del v\u00eddeo de nuestra entrevista a Giorgio Antonucci, premio Thomas Szasz en 2005.","breadcrumb":{"@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#primaryimage","url":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg","contentUrl":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2016\/12\/CrowdfundingOK.jpg","width":735,"height":553},{"@type":"BreadcrumbList","@id":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/edicion-y-subtitulacion-video-giorgio-antonucci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.perspectivasanomalas.org\/"},{"@type":"ListItem","position":2,"name":"Donation Forms","item":"https:\/\/www.perspectivasanomalas.org\/en\/donations\/"},{"@type":"ListItem","position":3,"name":"CROWDFUNDING Espacio e ideas: Edici\u00f3n y subtitulaci\u00f3n del v\u00eddeo de nuestra entrevista a Giorgio Antonucci"}]},{"@type":"WebSite","@id":"https:\/\/www.perspectivasanomalas.org\/#website","url":"https:\/\/www.perspectivasanomalas.org\/","name":"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas","description":"An\u00e1lisis del espacio para entender nuestra \u00e9poca. Cr\u00edtica de la sociedad neoliberal.","publisher":{"@id":"https:\/\/www.perspectivasanomalas.org\/#organization"},"alternateName":"Perspectivas an\u00f3malas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perspectivasanomalas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.perspectivasanomalas.org\/#organization","name":"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas","alternateName":"Perspectivas an\u00f3malas","url":"https:\/\/www.perspectivasanomalas.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.perspectivasanomalas.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2024\/05\/cropped-Group-52.png","contentUrl":"https:\/\/www.perspectivasanomalas.org\/wp-content\/uploads\/2024\/05\/cropped-Group-52.png","width":512,"height":512,"caption":"Perspectivas an\u00f3malas \u2022 ciudad arquitectura ideas"},"image":{"@id":"https:\/\/www.perspectivasanomalas.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perspectivasanomalas\/","https:\/\/x.com\/perspanomalas","https:\/\/www.linkedin.com\/company\/perspectivas-an\u00f3malas"]}]}},"_links":{"self":[{"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/give_forms\/1412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/give_forms"}],"about":[{"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/types\/give_forms"}],"author":[{"embeddable":true,"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/give_forms\/1412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/media\/1607"}],"wp:attachment":[{"href":"https:\/\/www.perspectivasanomalas.org\/en\/wp-json\/wp\/v2\/media?parent=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}